{"id":566,"date":"2021-04-18T02:39:14","date_gmt":"2021-04-18T01:39:14","guid":{"rendered":"http:\/\/www.buergerforum-europa.at\/?p=566"},"modified":"2021-04-19T23:57:41","modified_gmt":"2021-04-19T22:57:41","slug":"das-neue-buergerinnen-forum-europa","status":"publish","type":"post","link":"https:\/\/www.buergerforum-europa.at\/el\/das-neue-buergerinnen-forum-europa\/","title":{"rendered":"Das &#8220;neue&#8221; B\u00fcrgerInnen Forum Europa"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-el\">\u03a3\u03c5\u03b3\u03b3\u03bd\u03ce\u03bc\u03b7,\u03b1\u03c5\u03c4\u03ae \u03b7 \u03b5\u03b3\u03b3\u03c1\u03b1\u03c6\u03ae \u03b5\u03af\u03bd\u03b1\u03b9 \u03b4\u03b9\u03b1\u03b8\u03ad\u03c3\u03b9\u03bc\u03b7 \u03bc\u03cc\u03bd\u03bf \u03c3\u03c4\u03b1 <a href=\"https:\/\/www.buergerforum-europa.at\/de\/wp-json\/wp\/v2\/posts\/566\" class=\"qtranxs-available-language-link qtranxs-available-language-link-de\" title=\"Deutsch\">Deutsch<\/a>.<\/p><p>Das B\u00fcrgerInnen Forum Europa ist die \u00fcberparteiliche Plattform, die Europa \u00f6sterreichweit zum Thema macht. Wir verstehen uns als Plattform des Dialoges, der L\u00f6sungen sowie auch als kommunikatives Medium, das den Mehrwert der Europ\u00e4ischen Union und die Arbeit der Institutionen greifbarer machen soll.<\/p>\n<p><span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Mit der Mission, das europ\u00e4ische Bewusstsein in \u00d6sterreich zu st\u00e4rken, organisieren wir echte B\u00fcrgerdialoge in allen Bundesl\u00e4ndern, gestalten durchdachte Konzepte mit Expertinnen und Experten und bauen ein \u00f6sterreichweites Netzwerk von engagierten und aktiven Europ\u00e4erinnen und Europ\u00e4ern auf.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2>EUROPA GEMEINSAM WEITER DENKEN.<\/h2>\n<p>&nbsp;<\/p>\n<p>Gemeinsam mit Expertinnen und Experten, aber allen voran mit den B\u00fcrgerinnen und B\u00fcrgern \u00d6sterreichs, soll die Europ\u00e4ische Union verstanden, hinterfragt und gestaltet werden. Daf\u00fcr haben wir 5 Zukunftsthemen definiert, denen wir uns in den n\u00e4chsten 12 Monaten widmen m\u00f6chten. \u201eThink Europe\u201c soll hier, durch die Schaffung von Beir\u00e4ten, interessante neue Ans\u00e4tze liefern und die Grundlage unserer B\u00fcrgerInnendialoge sein.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2 class=\"phone-bigtext-2\">EUROPA<span class=\"Apple-converted-space\">\u00a0<\/span>IST SO INNOVATIV WIE DEINE VISIONEN.<\/h2>\n<p>&nbsp;<\/p>\n<p>\u201aCreate Europe\u2018 soll den Dialog zur Zukunft Europas nah zu den \u00d6sterreicherinnen und \u00d6sterreichern bringen. Keine klassischen Podiumsrunden, keine Vortr\u00e4ge. Das ist unser Anspruch. Wir wollen unsere Zukunftsthemen mit den \u00d6sterreicherinnen und \u00d6sterreichern debattieren und Ihre Gedanken und Anregungen mitnehmen. Unser Ziel ist es jedes unserer 5 Themen in allen 9 Bundesl\u00e4nder zu diskutieren. Hierbei unterst\u00fctzt ein ehrenamtliches Netzwerk an L\u00e4nderkoordinatoren und \u201eChangemakern\u201c.<\/p>\n<p>&nbsp;<\/p>\n<div class=\"h2 phone-bigtext-2\">\n<h2>UNSERE ZUKUNFTS&shy;THEMEN<\/h2>\n<\/div>\n<p>&nbsp;<\/p>\n<div class=\"body-2\">\n<div class=\"body\">\n<ol>\n<li><a href=\"https:\/\/www.buergerforum-europa.at\/thema\/innovation\/\">INNOVATION<\/a><\/li>\n<li><a href=\"https:\/\/www.buergerforum-europa.at\/thema\/wirtschaft-und-umwelt\/\">WIRTSCHAFT UND UMWELT<\/a><\/li>\n<li><a href=\"https:\/\/www.buergerforum-europa.at\/thema\/soziales\/\">SOZIALES<\/a><\/li>\n<li><a href=\"https:\/\/www.buergerforum-europa.at\/thema\/europa-in-der-welt\/\">EUROPA IN DER WELT<\/a><\/li>\n<li><a href=\"https:\/\/www.buergerforum-europa.at\/thema\/demokratie-und-recht\/\">DEMOKRATIE UND RECHT<\/a><\/li>\n<\/ol>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<h2 class=\"phone-bigtext-2\">EUROPA BRAUCHT DIE BESTEN K\u00d6PFE.<\/h2>\n<p>&nbsp;<\/p>\n<p>Das B\u00fcrgerInnen Forum Europa wird getragen von starken Pers\u00f6nlichkeiten &#8211; \u00dcberparteilich und mit hoher Expertise. Wir wollen Europa gestalten &#8211; gemeinsam mit den \u00d6sterreicherInnen. Denn: Europa entsteht im Dialog!<\/p>\n<p><a href=\"https:\/\/www.buergerforum-europa.at\/ueber-uns?preselect=vorstand\"><span class=\"underlined\">Zum neuen Vorstand<\/span><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Unsere 5 Beir\u00e4te sind die Grundpfeiler von \u201eThink Europe\u201c. Die Mitglieder &#8211; aus Politik, Wirtschaft, NGOs, Wissenschaft und Forschung &#8211; liefern durchdachte Konzepte und Anregungen, um unser Europa besser zu machen.<\/p>\n<p><span class=\"underlined\"><a href=\"https:\/\/www.buergerforum-europa.at\/ueber-uns\/\">Zu den Beir\u00e4ten<\/a><\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>\u03a3\u03c5\u03b3\u03b3\u03bd\u03ce\u03bc\u03b7,\u03b1\u03c5\u03c4\u03ae \u03b7 \u03b5\u03b3\u03b3\u03c1\u03b1\u03c6\u03ae \u03b5\u03af\u03bd\u03b1\u03b9 \u03b4\u03b9\u03b1\u03b8\u03ad\u03c3\u03b9\u03bc\u03b7 \u03bc\u03cc\u03bd\u03bf \u03c3\u03c4\u03b1 Deutsch.Das B\u00fcrgerInnen Forum Europa ist die \u00fcberparteiliche Plattform, die Europa \u00f6sterreichweit zum Thema macht. Wir verstehen uns als Plattform des Dialoges, der L\u00f6sungen sowie auch als kommunikatives Medium, das den Mehrwert der Europ\u00e4ischen Union und die Arbeit der Institutionen greifbarer machen soll. \u00a0 Mit der Mission, das europ\u00e4ische [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":324,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-566","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-update"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.buergerforum-europa.at\/el\/wp-json\/wp\/v2\/posts\/566","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.buergerforum-europa.at\/el\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.buergerforum-europa.at\/el\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.buergerforum-europa.at\/el\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.buergerforum-europa.at\/el\/wp-json\/wp\/v2\/comments?post=566"}],"version-history":[{"count":12,"href":"https:\/\/www.buergerforum-europa.at\/el\/wp-json\/wp\/v2\/posts\/566\/revisions"}],"predecessor-version":[{"id":580,"href":"https:\/\/www.buergerforum-europa.at\/el\/wp-json\/wp\/v2\/posts\/566\/revisions\/580"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.buergerforum-europa.at\/el\/wp-json\/wp\/v2\/media\/324"}],"wp:attachment":[{"href":"https:\/\/www.buergerforum-europa.at\/el\/wp-json\/wp\/v2\/media?parent=566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.buergerforum-europa.at\/el\/wp-json\/wp\/v2\/categories?post=566"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.buergerforum-europa.at\/el\/wp-json\/wp\/v2\/tags?post=566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}