{"id":986,"date":"2022-05-23T19:30:37","date_gmt":"2022-05-23T18:30:37","guid":{"rendered":"https:\/\/www.buergerforum-europa.at\/?post_type=themenkapitel&#038;p=986"},"modified":"2022-05-27T17:28:30","modified_gmt":"2022-05-27T16:28:30","slug":"umgang-mit-zielkonflikten","status":"publish","type":"themenkapitel","link":"https:\/\/www.buergerforum-europa.at\/el\/themenkapitel\/umgang-mit-zielkonflikten\/","title":{"rendered":"Umgang mit Zielkonflikten"},"content":{"rendered":"<p style=\"font-weight: 400;\">Unser bisheriges Wirtschaftssystem \u2013 beruhend auf Wirtschaftswachstum und fossilen Energien \u2013 hat uns in den Industrienationen viel Wohlstand gebracht. Wohlstand, der es uns erm\u00f6glicht hat, ein gutes Leben zu f\u00fchren, Sozialsysteme zu finanzieren und uns wirtschaftlich weiterzuentwickeln. Fakt ist aber auch, dass das fossile Wirtschaftssystem die gr\u00f6\u00dfte Krise der Menschheit verursacht hat \u2013 die Klima-, Biodiversit\u00e4ts- und Ressourcenkrise.<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\"><strong>Wirtschaft und Umwelt?<\/strong><\/p>\n<p style=\"font-weight: 400;\">Lange Zeit wurde die Einhaltung der planetarischen Grenzen in Widerspruch zu wirtschaftlichem Erfolg gesehen. Heute ist klar, wirtschaftlichen Erfolg werden diejenigen haben, die jetzt in Dekarbonisierung und Kreislaufwirtschaft investieren.<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">Mit dem Klimavertrag von Paris hat die Staatengemeinschaft festgelegt, die globale Erw\u00e4rmung auf 1,5 \u00b0C zu begrenzen. Alle Staaten sind verpflichtet ihre Zielsetzungen regelm\u00e4\u00dfig an diesen Zielpfad anzupassen. Daher ist klar, dass Rahmenbedingungen sich immer weiter an den Klimazielen orientieren werden. Viele Unternehmen haben das bereits erkannt und orientieren sich daher an den Zielen des Paris Agreement. Weltweit setzen viele Wirtschaftsinitiativen auf Dekarbonisierung als Gesch\u00e4ftsmodell und zeigen damit, dass Wirtschaft und Umwelt im 21. Jahrhundert nur gemeinsam gedacht werden kann.<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">Die EU definiert ihre Wirtschaftsstrategie als Green Deal f\u00fcr Europa. Der Green Deal setzt Ziele f\u00fcr verschiedene Umweltbereiche und dient gleichzeitig als Strategie f\u00fcr unterschiedliche Wirtschaftssektoren.<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">\u201eUmwelt-Wirtschaft\u201c bzw. Umweltvorgaben f\u00fcr die Wirtschaft wurden lange Zeit als Zielkonflikt mit Erfolg im internationalen Wettbewerb gesehen. Mit dem Green Deal stellt die EU auch klar, in welchen Wirtschaftsbereichen die EU eine Vorreiterrolle und Vorteile im internationalen Wettbewerb erlangen m\u00f6chte. Gerade in Innovation und Investition in Umwelttechnologien sowie Dekarbonisierungsl\u00f6sungen liegen die Chancen des europ\u00e4ischen Wirtschaftsstandorts.<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\"><strong>Umwelt &amp; Umwelt?<\/strong><\/p>\n<p style=\"font-weight: 400;\">Von Zielkonflikten zwischen Umwelt und Wirtschaft sind wir mittlerweile aber auch zu Zielkonflikten zwischen verschiedenen Umweltzielen gekommen. Behindern Arten- und Naturschutz die Energiewende? Kann Energiewende naturvertr\u00e4glich stattfinden? Verursachen Klimaschutz und Dekarbonisierung nur andere Ressourcenprobleme?<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">In all diesen Umweltbereichen sind die planetarischen Grenzen fast erreicht \/ \u00fcberschritten. Alle Umweltziele haben daher die gleiche Berechtigung und Dringlichkeit. Nachhaltiges Wirtschaften muss alle Aspekte ber\u00fccksichtigen. Deswegen m\u00fcssen L\u00f6sungen auch umfassend und branchen\u00fcbergreifend gedacht werden. Eindimensionale L\u00f6sungen werden nicht mehr funktionieren, wir brauchen systemische Ans\u00e4tze und Systemver\u00e4nderung.<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">Die Taxonomie als zentrales Element des Sustainable Finance Package der EU bietet hier erstmals einen Ansatz f\u00fcr ein Regelwerk, das verschiedene Umweltziele miteinander in Einklang bringt. Eine Wirtschaftsaktivit\u00e4t gilt dann als nachhaltig, wenn sie einen wesentlichen Beitrag zu einem der Umweltziele leistet, die jeweils anderen aber nicht gravierend beeintr\u00e4chtigt.<\/p>\n<p style=\"font-weight: 400;\">Wirtschaftliche Aktivit\u00e4ten k\u00f6nnen \u2013 auch wenn sie einen Beitrag zur Erreichung von Umweltzielen leisten, wie z.B. die Energiewende zur Erreichung der Klimaziele &#8211; Eingriffe bedeuten. Die Diskussion \u00fcber die Bewertung oder Abw\u00e4gung des Beitrags zum einen und die Beeintr\u00e4chtigung eines anderen Umweltzieles, wird oft in Genehmigungsverfahren gef\u00fchrt bzw. dorthin verschoben. Standards f\u00fcr nachhaltige Investitionen \/ Projekte, die unterschiedliche Umweltziele abbilden, k\u00f6nnen f\u00fcr die Umsetzung der Projekte hilfreich sein, damit die Interessensabw\u00e4gung nicht nur in Genehmigungsverfahren passiert. Rechtsmaterien sind daher zu evaluieren und zu pr\u00fcfen wie die Balance zwischen den \u00f6ffentlichen Interessen Klimaschutz, Energiewende, Biodiversit\u00e4t und anderen Umweltzielen hergestellt werden k\u00f6nnte.<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\"><strong>Akzeptanz &amp; Zeit &#8211; Klarheit &amp; Commitment<\/strong><\/p>\n<p style=\"font-weight: 400;\">Es ist klar, dass Projekte zur Umsetzung der Energiewende z\u00fcgig genehmigt und umgesetzt werden m\u00fcssen, damit die Klimaziele noch erreicht werden k\u00f6nnen. Nat\u00fcrlich muss in Genehmigungsverfahren eine Abw\u00e4gung verschiedener (\u00f6ffentlicher) Interessen erfolgen und eine Art \u00f6kologische Kosten-Nutzen-Analyse f\u00fcr einzelne Projekte durchgef\u00fchrt werden. Viele Verz\u00f6gerungen von Projektgenehmigungen werden auf die Debatte um Zielkonflikte bzw. mangelnde \u00f6ffentliche Akzeptanz zur\u00fcckgef\u00fchrt. Es gibt viele Ansatzpunkte in Genehmigungsverfahren, die die Situation f\u00fcr ProjektwerberInnen (Wirtschaft) und Umwelt bzw. \u00d6ffentlichkeit verbessern w\u00fcrden. F\u00fcr die Akzeptanz von Projekten und den Umgang mit Zielkonflikten ist jedenfalls eine \u00fcbergeordnete Planung, Klarheit und Commitment von Entscheidungstr\u00e4gerInnen notwendig.<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">Ja, die Energiewende wird man sehen. Eine Energiewende, die man nicht sieht, findet nicht statt. Daf\u00fcr braucht es Commitment (politischer) Entscheidungstr\u00e4gerInnen. Energiewende als gemeinsames gesellschaftliches Projekt erh\u00f6ht die Akzeptanz f\u00fcr einzelne Projekte. Die Politik darf daher nicht nur neutrale Beobachterin sein, es braucht ein klares Bekenntnis der Politik zu n\u00f6tigen Projekten (nat\u00fcrlich vorbehaltlich der n\u00f6tigen Genehmigungen). Grunds\u00e4tzliche Entscheidungen \u00fcber n\u00f6tige Projekte und die Abw\u00e4gung von Zielkonflikten darf aber nicht nur in Verfahren und an Unternehmen abgeschoben werden. Beteiligung ist wichtig, alle B\u00fcrgerInnen m\u00fcssen ihre Interessen einbringen k\u00f6nnen, daf\u00fcr gibt es mit der Aarhus-Konvention klare Vorgaben. Politik muss aber auch den Mut und Leadership aufbringen f\u00fcr \u00fcbergeordnete gesellschaftliche Interessen wie Klimaschutz, Energiewende und Versorgungssicherheit einzustehen.<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">Es braucht Klarheit: Klarheit \u00fcber die Bedeutung und das Ausma\u00df der Aufgabe. Die Bev\u00f6lkerung muss verstehen k\u00f6nnen, was Klima-, Biodiversit\u00e4ts- und Ressourcenkrise bedeuten und welche Handlungsnotwendigkeiten wir haben. Es braucht daher auch Klarheit, was Energiewende und Dekarbonisierung bedeuten. Welche und wie viele Projekte notwendig sein werden, welche Infrastruktur wir brauchen, um energieunabh\u00e4ngig zu werden, in welchen Zeithorizonten wir unser Wirtschafts- und Energiesystem umbauen m\u00fcssen.<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">Es braucht \u00fcbergeordnete Planung \u00fcber Notwendigkeiten der Energiewende und Notwendigkeiten f\u00fcr Natur- und Artenschutz. Planungen m\u00fcssen Verbindlichkeiten schaffen, f\u00fcr die Interessensabw\u00e4gung g\u00fcltig sein und damit Wirtschaft und Gesellschaft Orientierung geben.<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">Es braucht ein umfassendes und klares Bild, das die Notwendigkeiten der unterschiedlichen Umweltziele und den Weg dorthin beschreibt sowie die Chancen eines neuen Wirtschaftens im Einklang mit diesen Umweltzielen aufzeigt. Dazu braucht es klare Kommunikation, die unabh\u00e4ngig von kurzfristigen (Einzel)Interessen stattfindet.<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">Die Transformation von Wirtschaft und Gesellschaft braucht viele branchen\u00fcbergreifende L\u00f6sungen. F\u00fcr die Umsetzung der L\u00f6sungen brauchen wir Akzeptanz und m\u00fcssen die Bev\u00f6lkerung mitnehmen. Die Klimakrise gibt uns aber ein Zeitlimit. Nicht nur f\u00fcr notwendige technische, strukturelle und systemische Ver\u00e4nderungen stellt dieses Zeitlimit eine Herausforderung dar, auch demokratische Entscheidungsprozesse sind hier sehr gefordert. Nicht jedes einzelne Projekt wird \u00fcber Jahre diskutiert werden k\u00f6nnen. Dennoch m\u00fcssen Akzeptanz und Beteiligung sichergestellt werden. Ehrliche Information \u00fcber Notwendigkeiten von n\u00f6tigen Ma\u00dfnahmen, offene, klare und sich nicht nach potenziellen Schlagzeilen, sondern nach Fakten orientierende Kommunikation st\u00e4rken Akzeptanz und reduzieren Widerstand bei einzelnen Projekten.<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">Die Verfolgung der Ziele des Green Deal kann ein gemeinsames gesamtgesellschaftliches (Wirtschafts-)Projekt sein, das allen Europ\u00e4erInnen ein gutes Leben und wirtschaftliche Chancen bietet.<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">Wir sollten also von Zielkonflikten zu einem Ziel kommen: Ein Standort Europa, der durch Investitionen in und L\u00f6sungen f\u00fcr Klimaschutz, Biodiversit\u00e4t und Ressourceneffizienz wirtschaftlich vorne bleibt.<\/p>\n","protected":false},"featured_media":1029,"template":"","class_list":["post-986","themenkapitel","type-themenkapitel","status-publish","has-post-thumbnail","hentry"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.buergerforum-europa.at\/el\/wp-json\/wp\/v2\/themenkapitel\/986","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.buergerforum-europa.at\/el\/wp-json\/wp\/v2\/themenkapitel"}],"about":[{"href":"https:\/\/www.buergerforum-europa.at\/el\/wp-json\/wp\/v2\/types\/themenkapitel"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.buergerforum-europa.at\/el\/wp-json\/wp\/v2\/media\/1029"}],"wp:attachment":[{"href":"https:\/\/www.buergerforum-europa.at\/el\/wp-json\/wp\/v2\/media?parent=986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}